{"id":23646,"date":"2024-03-21T19:57:33","date_gmt":"2024-03-21T18:57:33","guid":{"rendered":"https:\/\/isocial.cat\/el-xat-leina-de-missatgeria-que-millora-la-comunicacio\/"},"modified":"2024-06-27T11:26:57","modified_gmt":"2024-06-27T09:26:57","slug":"el-chat-la-herramienta-de-mensajeria-que-mejora-la-comunicacion-y-la-atencion-al-usuario","status":"publish","type":"post","link":"https:\/\/isocial.cat\/es\/el-chat-la-herramienta-de-mensajeria-que-mejora-la-comunicacion-y-la-atencion-al-usuario\/","title":{"rendered":"El chat, la herramienta de mensajer\u00eda que mejora la comunicaci\u00f3n y la atenci\u00f3n al usuario"},"content":{"rendered":"\n<div class=\"wp-block-genesis-blocks-gb-container alignfull header--3 subhome--1 gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-genesis-blocks-gb-container container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<span class=\"parent--link separador producte animated fadeInUp slow\"><a href=\"https:\/\/isocial.cat\/es\/lab\/\">Lab<\/a> <a href=\"https:\/\/isocial.cat\/es\/productos\/\">Productos<\/a> <a href=\"https:\/\/isocial.cat\/es\/nidus-app\/\">Nidus<\/a><\/span>\n\n\n<h1 class=\"animated fadeInUp delay-200ms slow wp-block-post-title\">El chat, la herramienta de mensajer\u00eda que mejora la comunicaci\u00f3n y la atenci\u00f3n al usuario<\/h1>\n\n<div class=\"animated fadeInUp slow delay-500ms wp-block-post-date\"><time datetime=\"2024-03-21T19:57:33+01:00\">21 de marzo de 2024<\/time><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container container--2 subhome gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-genesis-blocks-gb-columns fila post animated fadeInUp slow gb-layout-columns-3 gb-3-col-widecenter\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-0 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\"><div class=\"taxonomy-category actualitat--categories wp-block-post-terms\"><a href=\"https:\/\/isocial.cat\/es\/category\/innovacion\/productos\/nidus-es\/\" rel=\"tag\">Nidus<\/a><\/div>\n\n<figure class=\"img-destacada wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Xat Nidus\" style=\"object-fit:cover;\" srcset=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat.webp 1200w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-500x281.webp 500w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-800x450.webp 800w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-300x169.webp 300w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-400x225.webp 400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container contingut-post gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<p class=\"lead-text has-large-font-size wp-block-paragraph\">Las nuevas versiones de las aplicaciones Nidus e iSocialPro incorporan ya la funcionalidad del chat. Esta herramienta de mensajer\u00eda integrada mejora la forma en que las personas usuarias y los profesionales interact\u00faan, y supone un paso significativo hacia una comunicaci\u00f3n y atenci\u00f3n m\u00e1s \u00e1gil y eficiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 te permite hacer el chat?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con el chat de <strong>Nidus<\/strong> y de <strong>iSocialPro<\/strong> podr\u00e1s <strong>contactar con tus usuarios y usuarias vinculados y con otros profesionales<\/strong>, y realizar un seguimiento de las conversaciones sin salir de la app.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como cualquier otra aplicaci\u00f3n de mensajer\u00eda, el chat de <strong>Nidus<\/strong> y de <strong>iSocialPro<\/strong> te permite <strong>enviar mensajes escritos y de voz<\/strong>, as\u00ed como compartir instant\u00e1neamente <strong>documentos, v\u00eddeos e im\u00e1genes<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, a diferencia de otros servicios, el <strong>chat de Nidus no est\u00e1 vinculado a ning\u00fan n\u00famero de tel\u00e9fono<\/strong> y las conversaciones pueden recuperarse f\u00e1cilmente accediendo al perfil del usuario desde cualquier dispositivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta nueva funcionalidad permite a las personas usuarias resolver consultas o dudas de forma inmediata, intercambiar m\u00e1s eficientemente documentos e informaci\u00f3n, organizar citas o reuniones con facilidad, enviar recordatorios\u2026 \u00a1y mucho m\u00e1s! Para acceder, s\u00f3lo es necesario entrar en la opci\u00f3n <strong>Mensajes<\/strong>, en la parte inferior de la pantalla. Tambi\u00e9n puedes enviar un mensaje directamente a trav\u00e9s del icono que se encuentra junto al perfil de cada usuario y profesional.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-23646_055c31-a8{margin:-17.5px;}.kb-gallery-type-masonry.kb-gallery-id-23646_055c31-a8 .kadence-blocks-gallery-item{padding:17.5px;}.kb-gallery-id-23646_055c31-a8 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-23646_055c31-a8 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-23646_055c31-a8 alignwide wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-23646_055c31-a8 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:452px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:80%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1.jpg\" width=\"452\" height=\"364\" alt=\"Xat Nidus\" data-full-image=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1.jpg\" data-light-image=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1.jpg\" data-id=\"23470\" class=\"wp-image-23470\" srcset=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1.jpg 452w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1-300x242.jpg 300w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-1-400x322.jpg 400w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:514px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:49%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2.jpg\" width=\"514\" height=\"256\" alt=\"Xat Nidus\" data-full-image=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2.jpg\" data-light-image=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2.jpg\" data-id=\"23474\" class=\"wp-image-23474\" srcset=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2.jpg 514w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2-500x249.jpg 500w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2-300x149.jpg 300w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/xat-nidus-2-400x199.jpg 400w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<div class=\"wp-block-genesis-blocks-gb-container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la funcionalidad del chat tambi\u00e9n permite la creaci\u00f3n de <strong>grupos de conversaci\u00f3n <\/strong>y de <strong>difusi\u00f3n de mensajes <\/strong>tanto con los usuarios como con otros profesionales.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 ventajas tiene el chat de Nidus y de iSocialPro?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las ventajas de disponer del chat son varias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mejora de la comunicaci\u00f3n<\/strong>: Facilita la interacci\u00f3n entre usuarios y profesionales.<\/li>\n\n\n\n<li>I<strong>ntercambio r\u00e1pido de informaci\u00f3n<\/strong>: Permite enviar desde mensajes de texto hasta archivos multimedia.<\/li>\n\n\n\n<li><strong>Confidencialidad<\/strong>: Hace posible una conexi\u00f3n \u00e1gil, manteniendo al mismo tiempo la confidencialidad sobre los tel\u00e9fonos de usuarios y profesionales.<\/li>\n\n\n\n<li><strong>Permite guardar las conversaciones<\/strong>: Las interacciones pueden recuperarse y continuar en cualquier momento y dispositivo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Con el chat, la comunicaci\u00f3n es m\u00e1s din\u00e1mica, la atenci\u00f3n al usuario m\u00e1s efectiva y las posibilidades de interacci\u00f3n m\u00e1s amplias. \u00a1Pru\u00e9balo y descubre c\u00f3mo esta nueva funcionalidad mejora tu experiencia con nuestras aplicaciones!<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<div  class=\"ultp-post-grid-block wp-block-ultimate-post-post-grid-1 ultp-block-27a652 container--2 subhome grid-darrers-projectes animated fadeInUp slow  \"><div class=\"ultp-block-wrapper\" ><div class=\"ultp-loading\"><div class=\"ultp-loading-spinner\" style=\"width:100%;height:100%\"><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><\/div><\/div><div class=\"ultp-heading-filter\"><div class=\"ultp-heading-filter-in\"><div class=\"ultp-filter-navigation\"><\/div><\/div><\/div><div class=\"ultp-block-items-wrap ultp-block-row ultp-pg1a-style1 ultp-grid1-responsive ultp-block-column-4 1 1 ultp-layout1\"><div class=\"ultp-block-item post-id-23646\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/es\/el-chat-la-herramienta-de-mensajeria-que-mejora-la-comunicacion-y-la-atencion-al-usuario\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Xat Nidus\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-600x600.webp\" \/><\/a><\/div><div class=\"ultp-block-content\"><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/es\/el-chat-la-herramienta-de-mensajeria-que-mejora-la-comunicacion-y-la-atencion-al-usuario\/\" >El chat, la herramienta de mensajer\u00eda que mejora la comunicaci\u00f3n y la atenci\u00f3n al usuario<\/a><\/h4><div class=\"ultp-block-excerpt\">Las nuevas versiones de las aplicaciones Nidus e iSocialPro incorporan ya la funcionalidad del chat.<\/div><\/div><\/div><\/div><\/div><div class=\"ultp-pagination-wrap ultp-pagination-ajax-action\" data-paged=\"1\" data-expost=\"\"  data-blockid=\"27a652\" data-postid=\"23646\" data-pages=\"1\" data-blockname=\"ultimate-post_post-grid-1\" data-selfpostid=\"yes\"><\/div><\/div><div class=\"pagination-block-html\" aria-hidden=\"true\" style=\"display: none;\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Las nuevas versiones de las aplicaciones Nidus e iSocialPro incorporan ya la funcionalidad del chat.<\/p>\n","protected":false},"author":1,"featured_media":23464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[442],"tags":[],"class_list":["post-23646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nidus-es","with-featured-image"],"acf":[],"taxonomy_info":{"category":[{"value":442,"label":"Nidus"}]},"featured_image_src_large":["https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat.webp",1200,675,false],"author_info":{"display_name":"admin","author_link":"https:\/\/isocial.cat\/es\/author\/ideadmin\/"},"comment_info":0,"category_info":[{"term_id":442,"name":"Nidus","slug":"nidus-es","term_group":0,"term_taxonomy_id":442,"taxonomy":"category","description":"","parent":266,"count":1,"filter":"raw","term_order":"0","cat_ID":442,"category_count":1,"category_description":"","cat_name":"Nidus","category_nicename":"nidus-es","category_parent":266}],"tag_info":false,"featured_image_src":"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-600x400.webp","featured_image_src_square":"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/nidus-xat-600x600.webp","_links":{"self":[{"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/posts\/23646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/comments?post=23646"}],"version-history":[{"count":4,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/posts\/23646\/revisions"}],"predecessor-version":[{"id":26581,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/posts\/23646\/revisions\/26581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/media\/23464"}],"wp:attachment":[{"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/media?parent=23646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/categories?post=23646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isocial.cat\/es\/wp-json\/wp\/v2\/tags?post=23646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}