{"id":19866,"date":"2023-11-08T11:13:15","date_gmt":"2023-11-08T10:13:15","guid":{"rendered":"https:\/\/isocial.cat\/oferta-formativa-beta\/"},"modified":"2025-05-05T13:10:14","modified_gmt":"2025-05-05T11:10:14","slug":"prestakuntza-eskaintza","status":"publish","type":"page","link":"https:\/\/isocial.cat\/eu\/prestakuntza-eskaintza\/","title":{"rendered":"Prestakuntza-eskaintza"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><div class=\"wp-block-genesis-blocks-gb-container alignfull header--3 subhome--1 campus gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-genesis-blocks-gb-container container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<span class=\"parent--link animated fadeInUp slow\"><a href=\"https:\/\/isocial.cat\/eu\/campusa\/\" data-type=\"page\" data-id=\"31\">Campus<\/a><\/span>\n\n\n<h1 class=\"animated fadeInUp delay-200ms slow wp-block-post-title\">Prestakuntza-eskaintza<\/h1>\n\n<div class=\"animated fadeInUp delay-500ms slow wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Prestakuntza-proposamenak eskaintzen dizkiegu, sektoreak dituen hobekuntza- eta eraldaketa-erronkei modu sortzaile eta berritzailean aurre egin nahi dieten, gizarte-zerbitzuetako profesional eta erakundeei. <\/p><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container container--2 subhome gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\"><div id=\"grid--woocommerce\" class=\"wp-block-product-blocks-product-grid-1 wopb-block-1c047a subhome--1 grid animated fadeInUp delay-1s slow idea-status \"><div class=\"wopb-block-wrapper\"><div class=\"wopb-wrapper-main-content\"><span class=\"wopb-no-product-found\">No products were found of your matching selection<\/span><\/div><\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76, .wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76[data-kb-block=\"kb-adv-heading19866_53dd52-76\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76[data-kb-block=\"kb-adv-heading19866_53dd52-76\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading19866_53dd52-76[data-kb-block=\"kb-adv-heading19866_53dd52-76\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading19866_53dd52-76 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading19866_53dd52-76\">Enkarguzko ikastaroak<\/h2>\n\n\n\n<p>Administrazioentzat eta erakundeentzat diseinatutako ikastaro pertsonalizatuak.<\/p>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id19866_640805-f1{margin-top:48px;margin-bottom:60px;}.kb-row-layout-id19866_640805-f1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id19866_640805-f1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id19866_640805-f1 > .kt-row-column-wrap{column-gap:64px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;grid-template-columns:minmax(0, calc(45% - ((64px * 1 )\/2)))minmax(0, calc(55% - ((64px * 1 )\/2)));}.kb-row-layout-id19866_640805-f1{background-color:#89266c;background-image:url('https:\/\/isocial.cat\/wp-content\/uploads\/2025\/04\/campus-header-scaled.webp');background-size:cover;background-position:0% 10%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id19866_640805-f1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id19866_640805-f1 > .kt-row-column-wrap{row-gap:48px;padding-top:32px;padding-right:32px;padding-bottom:32px;padding-left:32px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id19866_640805-f1 > .kt-row-column-wrap{padding-top:32px;padding-right:32px;padding-bottom:32px;padding-left:32px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id19866_640805-f1 alignnone kt-row-has-bg baner--campus wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column19866_cae095-a4 > .kt-inside-inner-col{display:flex;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col,.kadence-column19866_cae095-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column19866_cae095-a4{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column19866_cae095-a4{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column19866_cae095-a4{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column19866_cae095-a4{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column19866_cae095-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column19866_cae095-a4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image19866_4e2804-30:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kb-image19866_4e2804-30:not(.kb-image-is-ratio-size) .kb-img, .kb-image19866_4e2804-30.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-image19866_4e2804-30 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image19866_4e2804-30 size-large image-is-svg\"><a href=\"https:\/\/isocial.cat\/eu\/campus-isocial\/\" class=\"kb-advanced-image-link\"><img loading=\"lazy\" decoding=\"async\" width=\"446\" height=\"159\" src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2025\/04\/campus-logo-claim-es.svg\" alt=\"Campus iSocial\" class=\"kb-img wp-image-31966\"><\/a><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col{display:flex;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col,.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col{flex-direction:column;align-items:flex-end;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column19866_a6dfca-d4{position:relative;}@media all and (max-width: 1024px){.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kadence-column19866_a6dfca-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column19866_a6dfca-d4\"><div class=\"kt-inside-inner-col\"><style>.gb-6a03c1c509dcc{font-size: 36px;}@media only screen and (max-width: 600px) {.gb-6a03c1c509dcc{font-size: 30px!important;}}<\/style>\n<p class=\"gb-6a03c1c509dcc has-text-align-left text--baner--campus has-white-color has-text-color has-link-color has-large-font-size wp-elements-1ed048a74fe82422cb72b5190f7c78bf\">Dise&ntilde;amos la <strong>formaci&oacute;n<\/strong> que tu equipo necesita.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-fdcfc74e wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/isocial.cat\/eu\/campus-isocial\/\">Descubre como<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<div id=\"grid--woocommerce\" class=\"wp-block-product-blocks-product-grid-1 wopb-block-6acb04 encarrec subhome--1 grid animated fadeInUp delay-1s slow\"><div class=\"wopb-block-wrapper\"><div class=\"wopb-wrapper-main-content\"><div class=\"wopb-block-items-wrap wopb-block-row wopb-block-column-3\"><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"El reto de la desinstitucionalizaci&oacute;n\" href=\"https:\/\/isocial.cat\/eu\/producte\/el-reto-de-la-desinstitucionalizacion\/\">El reto de la desinstitucionalizaci&oacute;n<\/a><\/h2><div class=\"wopb-short-description\"><p> Adquiere los conocimientos necesarios para afrontar el reto de la desinstitucionalizaci&oacute;n de los servicios sociales (15 h) <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"24907\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"Medici&oacute;n y gesti&oacute;n del impacto social en el sector de los Servicios Sociales\" href=\"https:\/\/isocial.cat\/eu\/producte\/medicion-y-gestion-del-impacto-social-en-el-sector-de-los-servicios-sociales-copia-2\/\">Medici&oacute;n y gesti&oacute;n del impacto social en el sector de los Servicios Sociales<\/a><\/h2><div class=\"wopb-short-description\"><p> Mide el impacto socialde las acciones e intervenciones de tu organizaci&oacute;n con este curso (25 h., online) <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"20675\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"C&oacute;mo mejorar la comunicaci&oacute;n y la imagen de los Servicios Sociales\" href=\"https:\/\/isocial.cat\/eu\/producte\/como-mejorar-la-comunicacion-y-la-imagen-de-los-servicios-sociales\/\">C&oacute;mo mejorar la comunicaci&oacute;n y la imagen de los Servicios Sociales<\/a><\/h2><div class=\"wopb-short-description\"><p> Cambiar la manera de explicarnos para dar valor a lo que hacemos. (12 h., online o presencial) <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"19456\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"Herramientas para la gesti&oacute;n de equipos de los servicios sociales y la prevenci&oacute;n del estr&eacute;s\" href=\"https:\/\/isocial.cat\/eu\/producte\/herramientas-gestion-equipos-y-prevencion-estres\/\">Herramientas para la gesti&oacute;n de equipos de los servicios sociales y la prevenci&oacute;n del estr&eacute;s<\/a><\/h2><div class=\"wopb-short-description\"><p> De la queja al compromiso. M&eacute;todos para poder crecer, actuar, gestionar el estr&eacute;s y relacionarse en un entorno laboral saludable y de calidad (20 h, online o semipresencial). <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"20796\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title='De la Atenci&oacute;n Centrada en la Persona al \"Self-directed Support\"' href=\"https:\/\/isocial.cat\/eu\/producte\/de-la-atencion-centrada-en-la-persona-al-self-directed-support\/\">De la Atenci&oacute;n Centrada en la Persona al &ldquo;Self-directed Support&rdquo;<\/a><\/h2><div class=\"wopb-short-description\"><p> Nuevos modelos de intervenci&oacute;n en los servicios sociales p&uacute;blicos y del tercer sector. On-line (16,5 horas) <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"19465\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"Herramientas para la transformaci&oacute;n digital de los Servicios Sociales B&aacute;sicos\" href=\"https:\/\/isocial.cat\/eu\/producte\/herramientas-para-la-transformacion-digital-de-los-servicios-sociales-basicos\/\">Herramientas para la transformaci&oacute;n digital de los Servicios Sociales B&aacute;sicos<\/a><\/h2><div class=\"wopb-short-description\"><p> Programa formativo para personal t&eacute;cnico de Servicios Sociales de los entes locales. En l&iacute;nea (15h). <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"19475\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"Innovaci&oacute;n y gesti&oacute;n del cambio\" href=\"https:\/\/isocial.cat\/eu\/producte\/innovacion-y-gestion-del-cambio\/\">Innovaci&oacute;n y gesti&oacute;n del cambio<\/a><\/h2><div class=\"wopb-short-description\"><p> Management y habilidades para la mejora continua. En l&iacute;nea (10 horas) <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"19679\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><div class=\"wopb-block-item \"><div class=\"wopb-block-content-wrap\"><h2 class=\"wopb-block-title\"><a title=\"La intervenci&oacute;n comunitaria en los Servicios Sociales B&aacute;sicos\" href=\"https:\/\/isocial.cat\/eu\/producte\/la-intervencion-comunitaria-en-los-servicios-sociales-basicos\/\">La intervenci&oacute;n comunitaria en los Servicios Sociales B&aacute;sicos<\/a><\/h2><div class=\"wopb-short-description\"><p> El trabajo comunitario como forma de intervenci&oacute;n social. En l&iacute;nea (10,5 horas). <\/p>&hellip;<\/div><div class=\"wopb-product-btn\"><div class=\"wopb-product-btn \"><span class=\"wopb-cart-action \" data-postid=\"19485\"><a href=\"https:\/\/isocial.cat\/eu\/cart\/\" class=\"wopb-cart-active\">View Cart<\/a><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>Prestakuntza-proposamenak eskaintzen dizkiegu, sektoreak dituen hobekuntza- eta eraldaketa-erronkei modu sortzaile eta berritzailean aurre egin nahi dieten, gizarte-zerbitzuetako profesional eta erakundeei.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-builder.php","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-19866","page","type-page","status-publish","hentry","post","without-featured-image"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/isocial.cat\/eu\/author\/ideadmin\/"},"comment_info":0,"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/pages\/19866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/comments?post=19866"}],"version-history":[{"count":14,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/pages\/19866\/revisions"}],"predecessor-version":[{"id":32346,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/pages\/19866\/revisions\/32346"}],"wp:attachment":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/media?parent=19866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}