{"id":29819,"date":"2024-12-18T14:32:09","date_gmt":"2024-12-18T13:32:09","guid":{"rendered":"https:\/\/isocial.cat\/josep-maria-sole-para-innovar-hay-que-atreverse-y-el-atrevimiento-implica-asumir-el-riesgo-a-equivocarse\/"},"modified":"2024-12-18T14:32:09","modified_gmt":"2024-12-18T13:32:09","slug":"josep-maria-sole-para-innovar-hay-que-atreverse-y-el-atrevimiento-implica-asumir-el-riesgo-a-equivocarse","status":"publish","type":"post","link":"https:\/\/isocial.cat\/eu\/josep-maria-sole-para-innovar-hay-que-atreverse-y-el-atrevimiento-implica-asumir-el-riesgo-a-equivocarse\/","title":{"rendered":"Josep Maria Sol\u00e9: &#8220;Para innovar, hay que atreverse, y el atrevimiento implica asumir el riesgo a equivocarse&#8221;"},"content":{"rendered":"\n<div class=\"wp-block-genesis-blocks-gb-container alignfull header--3 subhome--1 gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-genesis-blocks-gb-container container gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<span class=\"parent--link separador animated fadeInUp slow\"><a href=\"https:\/\/isocial.cat\/eu\/argitalpenak\/\" data-type=\"page\" data-id=\"51\">Argitalpenak<\/a> <a href=\"https:\/\/isocial.cat\/eu\/elkarrizketak\/\" data-type=\"page\" data-id=\"12741\">Elkarrizketak<\/a><\/span>\n\n\n<h1 class=\"animated fadeInUp delay-200ms slow wp-block-post-title\">Josep Maria Sol\u00e9: &#8220;Para innovar, hay que atreverse, y el atrevimiento implica asumir el riesgo a equivocarse&#8221;<\/h1>\n\n<div class=\"animated fadeInUp slow delay-500ms wp-block-post-date\"><time datetime=\"2024-12-18T14:32:09+01:00\">18 de Diciembre de 2024<\/time><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container container--2 subhome gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<div class=\"wp-block-genesis-blocks-gb-columns fila post animated fadeInUp slow gb-layout-columns-3 gb-3-col-widecenter\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-0 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\"><div class=\"taxonomy-category actualitat--categories wp-block-post-terms\"><a href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\" rel=\"tag\">Destacados Home<\/a><span class=\"wp-block-post-terms__separator\">, <\/span><a href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\" rel=\"tag\">Elkarrizketak<\/a><\/div>\n\n<figure class=\"img-destacada wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Entrevista a Josep Maria Sol\u00e9 - Per innovar, cal atrevir-s&#039;hi\" style=\"object-fit:cover;\" srcset=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole.png 1200w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-500x263.png 500w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-800x420.png 800w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-300x158.png 300w, https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-400x210.png 400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-container contingut-post gb-block-container\"><div class=\"gb-container-inside\"><div class=\"gb-container-content\">\n<p class=\"lead-text has-large-font-size wp-block-paragraph\">Josep Maria Sol\u00e9 es abogado y director de la Fundaci\u00f3 Support-Girona, patrono y presidente del Consell Social de la Fundaci\u00f3 Institut Guttmann, vicepresidente de la Fundaci\u00f3 DRISSA y miembro de la junta directiva de la European Association of Service Providers for Persons with Disabilities (EASPD), entre otros cargos. Desde 2024, tambi\u00e9n es presidente de la Fundaci\u00f3 iSocial, donde ha tomado el relevo de Montse Cervera. Hablamos con \u00e9l para compartir su visi\u00f3n sobre la fundaci\u00f3n y sobre la necesidad de innovar en el sector social<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82, .wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82[data-kb-block=\"kb-adv-heading29816_1455b0-82\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82[data-kb-block=\"kb-adv-heading29816_1455b0-82\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_1455b0-82[data-kb-block=\"kb-adv-heading29816_1455b0-82\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_1455b0-82 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_1455b0-82\">\u00bfQu\u00e9 significa para ti asumir la presidencia de una fundaci\u00f3n que tiene por objetivo impulsar la innovaci\u00f3n social?<\/h3>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">Tal como la entiendo, la Fundaci\u00f3 iSocial ha sido desde el principio un proyecto cooperativo de las organizaciones que formamos parte de ella. Asumir la presidencia no es m\u00e1s que cumplir un rol del que alguien se tiene que hacer cargo. Mi prop\u00f3sito como presidente es procurar que participe al m\u00e1ximo el talento que hay en todas las entidades que forman parte del ecosistema de iSocial. Pero tambi\u00e9n me gustar\u00eda intentar llegar a otras organizaciones, a una parte del \u00e1mbito del sector social a la que todav\u00eda no hemos podido llegar. Solo las alianzas nos har\u00e1n crecer. No basta con tener talento y grandes ideas, sino que son sobre todo las alianzas las que permitir\u00e1n que las ideas tomen forma y puedan materializarse. En este sentido, una persona sola puede hacer poco, a no ser que pueda sumar muchas voluntades. Y esta es, pienso, la finalidad principal del rol que ahora me toca asumir.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08, .wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08[data-kb-block=\"kb-adv-heading29816_5609d5-08\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08[data-kb-block=\"kb-adv-heading29816_5609d5-08\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_5609d5-08[data-kb-block=\"kb-adv-heading29816_5609d5-08\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_5609d5-08 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_5609d5-08\">\u00bfPor qu\u00e9 es importante innovar en el sector social?<\/h3>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">Es importante sobre todo generar una actitud innovadora, y que la innovaci\u00f3n llegue tanto a la intervenci\u00f3n directa con las personas y colectivos que lo necesitan \u2013donde el sector social materializa su misi\u00f3n y sus valores\u2013 como a la manera de organizar los mecanismos que nos permiten esta intervenci\u00f3n. Hay que repensar estos mecanismos para poder tener una incidencia m\u00e1s significativa, m\u00e1s transformadora en las vidas de las personas y en la sociedad en su conjunto.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00, .wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00[data-kb-block=\"kb-adv-heading29816_8a87c2-00\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00[data-kb-block=\"kb-adv-heading29816_8a87c2-00\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_8a87c2-00[data-kb-block=\"kb-adv-heading29816_8a87c2-00\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_8a87c2-00 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_8a87c2-00\">\u00bfA qu\u00e9 te refieres cuando hablas de introducir la innovaci\u00f3n en la organizaci\u00f3n de los recursos?<\/h3>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">Este es un punto en el que vamos un poco atrasados respecto a otros sectores, como por ejemplo el sanitario, donde se ha dado a la gesti\u00f3n un valor intr\u00ednseco y nadie llega a cargos de gesti\u00f3n solo a partir de la pr\u00e1ctica. El sector sanitario es muy consciente de que es un sector depositario de muchos esfuerzos sociales \u2013en forma de presupuestos, recursos&#8230;\u2013 y que, por tanto, debe gestionarse con criterios de <em>management<\/em>. En el mundo social, en cambio, a\u00fan pasa que muchas personas llegan a roles de direcci\u00f3n o roles estrat\u00e9gicos sin haberlo previsto, y quiz\u00e1s sin haber recibido la formaci\u00f3n adecuada para ejercer este rol. <\/p>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">Hace falta que la innovaci\u00f3n pase a formar parte de la gesti\u00f3n de las entidades, lo que no quiere decir, evidentemente, renunciar a aportar valor social. En otros sectores no cuesta tanto, y cuando se encuentra una soluci\u00f3n que aporta valor, se explica, se presenta en congresos, etc. Nosotros tenemos poca tradici\u00f3n de esto, y a menudo muchas de las actividades que se generan alrededor del sector social son para darle vueltas a los mismos problemas. Falta un debate real sobre c\u00f3mo avanzar y hacer las cosas mejor. Y esto no siempre significa disrupci\u00f3n, aunque a veces s\u00ed.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3, .wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3[data-kb-block=\"kb-adv-heading29816_412edf-a3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3[data-kb-block=\"kb-adv-heading29816_412edf-a3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_412edf-a3[data-kb-block=\"kb-adv-heading29816_412edf-a3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_412edf-a3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_412edf-a3\">Mirando atr\u00e1s, \u00bfcu\u00e1les son los principales logros de la Fundaci\u00f3 iSocial en sus 6 a\u00f1os de vida?<\/h3>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">En primer lugar, haber consolidado su propia existencia y una estructura organizativa m\u00ednima que permite afrontar ya encargos con m\u00e1s ambici\u00f3n. Al principio, todos los que estuvimos involucrados invertimos recursos e ideas, pero b\u00e1sicamente cont\u00e1bamos con el recurso humano de uno de los fundadores, el actual director, Toni Codina. Hoy, Toni Codina est\u00e1 acompa\u00f1ado de otro talento que hace que podamos materializar m\u00e1s cosas, y por tanto, aquellas ideas que llegan al ecosistema de iSocial tienen muchas m\u00e1s posibilidades de ser implantadas, probadas, testeadas\u2026 y acabar siendo una realidad escalable. Al principio todo esto parec\u00eda muy lejano.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a, .wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a[data-kb-block=\"kb-adv-heading29816_c76f1c-3a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a[data-kb-block=\"kb-adv-heading29816_c76f1c-3a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_c76f1c-3a[data-kb-block=\"kb-adv-heading29816_c76f1c-3a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_c76f1c-3a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_c76f1c-3a\">\u00bfQu\u00e9 papel juega la Fundaci\u00f3n iSocial dentro del ecosistema de innovaci\u00f3n social en Catalu\u00f1a y en Europa?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Somos una pieza m\u00e1s; no podemos pensar que hemos llegado y transformado la visi\u00f3n del sector. Sin embargo, creo que somos una pieza bastante original. No hay tantas entidades en las que confluyan esta cantidad de organizaciones de intervenci\u00f3n independientes, sin estar organizadas como sector o federaci\u00f3n ni depender de una administraci\u00f3n o gobierno. Las entidades que participan en iSocial lo hacen libremente, y esa libertad y autonom\u00eda, a la hora de plantearnos las l\u00edneas de acci\u00f3n de la Fundaci\u00f3n, son muy valiosas. Ahora bien, como dec\u00eda, existen otros agentes, y tal vez el siguiente paso sea trabajar con ellos e incorporarlos para crear un ecosistema que impregne al conjunto del sector y pueda mejorar la manera en que hacemos las cosas.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f, .wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f[data-kb-block=\"kb-adv-heading29816_681ca3-8f\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f[data-kb-block=\"kb-adv-heading29816_681ca3-8f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_681ca3-8f[data-kb-block=\"kb-adv-heading29816_681ca3-8f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_681ca3-8f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_681ca3-8f\">\u00bfC\u00f3mo valoras el estado actual del sector social?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos en un momento complicado, porque Europa, y el mundo en general, est\u00e1n tendiendo hacia una geopol\u00edtica muy compleja en la que algunos de los valores que han inspirado las pol\u00edticas en el \u00e1mbito social, sobre todo en Europa, est\u00e1n en cuesti\u00f3n. Y nadie lo dice expl\u00edcitamente, pero algunas de las propuestas que se plantean a la poblaci\u00f3n y que son votadas \u2013a veces de manera mayoritaria\u2013 no cuentan con las ideas de solidaridad, de cohesi\u00f3n\u2026 que el sector social requiere para poder apoyar a las personas y colectivos que lo necesitan. Las ideas que hoy parecen ganar terreno no siempre est\u00e1n alineadas con el ideal de una sociedad inclusiva donde todos puedan participar sin sentirse excluidos. Hay una tendencia individualista, fruto de un liberalismo mal entendido, que deshumaniza al d\u00e9bil, a aquel que no tiene recursos para competir. Y yo creo que debemos ser capaces, desde el sector social, de ser un contrapeso para impedir que esta visi\u00f3n termine dominando. Debemos poner lo colectivo, la sociedad en su conjunto y especialmente a los m\u00e1s excluidos, como prioridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y Europa deber\u00eda ser un basti\u00f3n, porque muchos otros pa\u00edses no han tenido esta visi\u00f3n del estado del bienestar, de una sociedad en la que se busca el reequilibrio a trav\u00e9s de la contribuci\u00f3n de los que m\u00e1s tienen para reducir las condiciones desfavorables de los que menos tienen. El sector social necesita innovar para demostrar que puede hacer las cosas bien, con una gesti\u00f3n eficiente de los recursos, y al mismo tiempo transformando y aportando valor al conjunto. Y esto no es f\u00e1cil, porque hay que darle un prop\u00f3sito a todo lo que se hace, y a menudo este prop\u00f3sito es demasiado t\u00e1ctico y no tiene la mirada estrat\u00e9gica que ahora necesitamos.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad, .wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad[data-kb-block=\"kb-adv-heading29816_eb5311-ad\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad[data-kb-block=\"kb-adv-heading29816_eb5311-ad\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_eb5311-ad[data-kb-block=\"kb-adv-heading29816_eb5311-ad\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_eb5311-ad wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_eb5311-ad\">\u00bfQu\u00e9 otros retos tiene por delante el tercer sector social?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El sector social tendr\u00e1 que adaptarse a un cambio social inevitable: la progresiva ampliaci\u00f3n del colectivo de personas mayores \u2013algunas de ellas con necesidades de apoyo\u2013 dentro del conjunto de la poblaci\u00f3n. Este es un factor ineludible, y puede tener varias respuestas, algunas de las cuales, por supuesto, no interesan al sector social. Una de ellas es mercantilizar por completo el sector del apoyo y los cuidados, buscando \u00fanicamente la rentabilidad y la m\u00ednima cobertura de necesidades. Desde el sector social, debemos defender valores de derechos humanos que impliquen que estos apoyos y cuidados sean inclusivos y cuenten con la participaci\u00f3n de las personas, sin dejar a nadie atr\u00e1s ni convertir a aquellos con menos recursos en ciudadanos de segunda. En este sentido, tenemos un reto, porque el sector mercantil tiende a abaratar precios y a industrializar los productos, diciendo: \u201cnosotros lo haremos m\u00e1s barato\u201d. Estoy a favor de industrializar todos aquellos procesos que no aportan valor a\u00f1adido, como la burocracia, pero solo en la medida en que esto nos permita disponer de m\u00e1s recursos para humanizar, para centrarnos m\u00e1s en las relaciones humanas, que en \u00faltima instancia es lo que mejora la vida de todos. Creo que este deber\u00eda ser el objetivo del sector social.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03, .wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03[data-kb-block=\"kb-adv-heading29816_9c7abf-03\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03[data-kb-block=\"kb-adv-heading29816_9c7abf-03\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_9c7abf-03[data-kb-block=\"kb-adv-heading29816_9c7abf-03\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_9c7abf-03 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_9c7abf-03\">Muchos de los proyectos de la Fundaci\u00f3n iSocial se han impulsado mediante financiaciones coyunturales, como los fondos Next Generation, creados en respuesta a la crisis provocada por la pandemia de la COVID-19. M\u00e1s all\u00e1 de este tipo de financiaci\u00f3n, \u00bfcu\u00e1l es el desaf\u00edo de la Fundaci\u00f3n a la hora de buscar recursos y sacar adelante nuevos proyectos?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El desaf\u00edo es concienciar a la sociedad en general, pero especialmente al sector pol\u00edtico y a los gobiernos, sobre la necesidad de replantear de ra\u00edz el sector social, ya que actualmente no cumple con los est\u00e1ndares de derechos humanos. Por ejemplo, buena parte del sector social ofrece apoyos basados en la idea de institucionalizaci\u00f3n, es decir, en la provisi\u00f3n de un mismo servicio para un colectivo de personas, sin considerar las necesidades espec\u00edficas de cada individuo. Todo el gasto destinado al \u00e1mbito residencial o a gran parte de la atenci\u00f3n diurna para colectivos como las personas mayores o las personas con discapacidad sigue basado en esta l\u00f3gica. Y no somos conscientes de que esto, desde una perspectiva estrictamente basada en los derechos humanos, est\u00e1 obsoleto. Hay que ofrecer a cada persona oportunidades para desarrollar su vida, vivirla de manera plena e independiente y, al mismo tiempo, ser incluida en la comunidad. Para lograrlo, es necesario proporcionar los apoyos que cada persona requiera como individuo, sin pensar \u00fanicamente en t\u00e9rminos colectivos. Esta transformaci\u00f3n ni siquiera ha sido contemplada en el uso de fondos como los Next Generation, que a menudo han servido para reforzar el enfoque institucional.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3, .wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3[data-kb-block=\"kb-adv-heading29816_9ff934-f3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3[data-kb-block=\"kb-adv-heading29816_9ff934-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_9ff934-f3[data-kb-block=\"kb-adv-heading29816_9ff934-f3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_9ff934-f3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_9ff934-f3\">\u00bfEn qu\u00e9 sentido?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En muchos casos, por ejemplo, se han destinado a la construcci\u00f3n de espacios residenciales, que pueden ser una alternativa, pero que lamentablemente acaban convirti\u00e9ndose en la \u00fanica opci\u00f3n para muchas personas. Espero que el desarrollo de esta l\u00ednea de pensamiento sobre apoyos para una vida plena siga impulsando la innovaci\u00f3n y que iSocial tenga un espacio para introducir nuevas ideas y proyectos. No puedo concebir que, aunque finalice el impulso de los fondos Next Generation o surjan pol\u00edticas presupuestarias de contenci\u00f3n fiscal, no se contin\u00fae profundizando en la idea de la individualizaci\u00f3n y personalizaci\u00f3n de los apoyos y los cuidados, en el derecho a elegir c\u00f3mo quieres vivir y, en caso de optar por permanecer en tu entorno habitual, en garantizar que lleguen los mecanismos de apoyo necesarios de manera suficiente y adecuada. A\u00fan estamos muy lejos de poder ofrecer todo esto, y la incorporaci\u00f3n de nuevas tecnolog\u00edas para hacer m\u00e1s eficientes algunos de estos procesos sigue estando en sus inicios. Tambi\u00e9n es necesario replantear la organizaci\u00f3n de los recursos. Cuando contamos con m\u00e1s recursos, a menudo reproducimos los mismos modelos que ya ten\u00edamos, sin pensar que quiz\u00e1 sea necesario reorganizarlo todo de manera diferente.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe, .wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe[data-kb-block=\"kb-adv-heading29816_883c19-fe\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe[data-kb-block=\"kb-adv-heading29816_883c19-fe\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_883c19-fe[data-kb-block=\"kb-adv-heading29816_883c19-fe\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_883c19-fe wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_883c19-fe\">\u00bfCu\u00e1l deber\u00eda ser el papel de los organismos p\u00fablicos en relaci\u00f3n con la innovaci\u00f3n social?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, no deber\u00edan poner trabas, y en segundo lugar, deber\u00edan fomentarla. Es fundamental que busquen evidencias de qu\u00e9 iniciativas funcionan y, para obtener esas evidencias, es necesario permitir que se prueben. Hoy en d\u00eda, existe un miedo exacerbado a probar cosas nuevas. Si no se prueban alternativas, no se pueden descartar aquellas que no son adecuadas. A menudo, continuamos con lo tradicional simplemente porque es lo conocido, sin atrevernos a explorar nuevas propuestas de intervenci\u00f3n, organizaci\u00f3n de recursos o movilizaci\u00f3n de las energ\u00edas de la comunidad. Estas opciones, al no haberse probado, no pueden ser evidenciadas y, por lo tanto, no reciben apoyo de recursos p\u00fablicos. Innovar requiere atreverse, y ese atrevimiento debe incluir la aceptaci\u00f3n del riesgo de equivocarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tendencia actual va en direcci\u00f3n contraria. Con frecuencia se perpet\u00faan los errores de enfoques que en su momento funcionaron o parecieron funcionar, aunque no hayan sido revalidados de manera moderna y contrastada. Es posible que estos planteamientos ya no sean eficaces, y aun as\u00ed se siguen destinando recursos p\u00fablicos a ellos. Si no hay inquietud y valent\u00eda para asumir riesgos, continuaremos haciendo siempre lo mismo, y para seguir igual no es necesario innovar.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30, .wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30[data-kb-block=\"kb-adv-heading29816_fc6fdd-30\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30[data-kb-block=\"kb-adv-heading29816_fc6fdd-30\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_fc6fdd-30[data-kb-block=\"kb-adv-heading29816_fc6fdd-30\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_fc6fdd-30 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_fc6fdd-30\">\u00bfC\u00f3mo podemos fomentar un di\u00e1logo productivo entre los diferentes agentes implicados en la innovaci\u00f3n social?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estableciendo m\u00faltiples mecanismos de interacci\u00f3n entre todos los actores del sistema. Es imprescindible facilitar que las personas puedan expresar, en su propia voz, qu\u00e9 sienten al recibir intervenciones del \u00e1mbito social: qu\u00e9 encuentran a faltar, qu\u00e9 les funciona y qu\u00e9 no. Frecuentemente, estas personas no son tenidas en cuenta, especialmente si enfrentan dificultades para formular lo que desean o necesitan. Por ello, el apoyo en la toma de decisiones o en la comunicaci\u00f3n de la propia voluntad son \u00e1reas donde claramente debemos innovar. Tambi\u00e9n ocurre a menudo que las personas acompa\u00f1adas no pueden aportar valor en forma de opini\u00f3n sobre posibles alternativas porque estas nunca les han sido ofrecidas y, por ende, las desconocen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, es esencial involucrar a todos los agentes, incluyendo la inmensa fuerza laboral que se incorpora al sector social, a menudo en condiciones muy precarias. Asimismo, se debe ampliar la perspectiva para incluir todo tipo de organizaciones de manera transversal, sin prejuicios, salvo uno fundamental: el respeto a los derechos humanos. Si alguien defiende posiciones que no est\u00e9n alineadas con una perspectiva de derechos humanos, deber\u00edamos ser capaces de apartarlo del sistema.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c, .wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c[data-kb-block=\"kb-adv-heading29816_1797fc-3c\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c[data-kb-block=\"kb-adv-heading29816_1797fc-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading29816_1797fc-3c[data-kb-block=\"kb-adv-heading29816_1797fc-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading29816_1797fc-3c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading29816_1797fc-3c\">\u00bfCu\u00e1l crees que es el principal obst\u00e1culo para la innovaci\u00f3n social en el tercer sector, y c\u00f3mo podr\u00edamos superarlo?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El obst\u00e1culo principal es el miedo, y la soluci\u00f3n radica en el atrevimiento: el atrevimiento a hacer cosas distintas y desde perspectivas diversas. Este atrevimiento puede significar brindar un verdadero apoyo a la autonom\u00eda de las personas, dejando de ser los grandes vigilantes de la prevenci\u00f3n del riesgo. Es crucial permitir que las personas tomen sus propias decisiones y acompa\u00f1arlas en este proceso, sin prejuzgar ni intentar impedir que lleven a cabo sus elecciones, incluso si estas no nos agradan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, los mecanismos que empleamos tienden a evitar que las decisiones que no aprobamos se realicen. Esto ocurre en casos que van desde las personas mayores hasta las personas con discapacidad o con problemas de salud mental. La aversi\u00f3n al riesgo est\u00e1 profundamente arraigada, tanto en las intervenciones como en el ensayo de pol\u00edticas innovadoras. Para verificar si estas pol\u00edticas funcionan, necesitamos un punto de valent\u00eda, y esto, al final, es una cuesti\u00f3n de actitud.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n\n<\/div><\/div><\/div>\n\n\n<div  class=\"ultp-post-grid-block wp-block-ultimate-post-post-grid-1 ultp-block-36b070 container--2 subhome grid-darrers-projectes animated fadeInUp slow  \"><div class=\"ultp-block-wrapper\" ><div class=\"ultp-loading\"><div class=\"ultp-loading-spinner\" style=\"width:100%;height:100%\"><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><div><\/div><\/div><\/div><div class=\"ultp-heading-filter\"><div class=\"ultp-heading-filter-in\"><div class=\"ultp-heading-wrap ultp-heading-style1 ultp-heading-left\"><p class=\"ultp-heading-inner\"><span>Entrevistes<\/span><\/p><\/div><div class=\"ultp-filter-navigation\"><\/div><\/div><\/div><div class=\"ultp-block-items-wrap ultp-block-row ultp-pg1a-style1 ultp-grid1-responsive ultp-block-column-4 1 1 ultp-layout1\"><div class=\"ultp-block-item post-id-35351\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/jordi-amat-director-del-area-de-tic-del-departamento-de-derechos-sociales-e-inclusion-el-objetivo-de-wsocial-es-que-la-informacion-social-este-al-servicio-de-todo-el-ecosistema-social\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Usuari utilitzant wSocial\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2025\/11\/wSocial-4-600x600.png\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-argitalpenak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/\"  >Argitalpenak<\/a><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/jordi-amat-director-del-area-de-tic-del-departamento-de-derechos-sociales-e-inclusion-el-objetivo-de-wsocial-es-que-la-informacion-social-este-al-servicio-de-todo-el-ecosistema-social\/\" >Jordi Amat, director del \u00c1rea de TIC del Departamento de Derechos Sociales e Inclusi\u00f3n: &#8220;El objetivo de wSocial es que la informaci\u00f3n est\u00e9 al servicio de todo el ecosistema social&#8221;<\/a><\/h4><div class=\"ultp-block-excerpt\">Jordi Amat es director del \u00c1rea de TIC del Departamento de Derechos Sociales e Inclusi\u00f3n de la Generalitat de Catalunya. Hablamos con \u00e9l para conocer mejor wSocial, su funcionamiento y el despliegue previsto.<\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-33694\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/laura-roig-logopeda-en-audivers-360o-la-terapia-inmersiva-nos-permite-ayudar-a-las-personas-con-sordera-a-comprender-mejor-lo-que-sucede-a-su-alrededor\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Hablamos con la logopeda Laura Roig sobre Audivers 360\u00ba, el proyecto ganador del Premio GrausTIC a la Integraci\u00f3n Social a trav\u00e9s de la Digitalizaci\u00f3n otorgado por la Fundaci\u00f3n iSocial en el a\u00f1o 2023\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2025\/07\/BI-1-min-1-600x600.png\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/laura-roig-logopeda-en-audivers-360o-la-terapia-inmersiva-nos-permite-ayudar-a-las-personas-con-sordera-a-comprender-mejor-lo-que-sucede-a-su-alrededor\/\" >Laura Roig, logopeda en Audivers 360\u00ba: &#8220;La terapia inmersiva nos permite ayudar a las personas con sordera a comprender mejor lo que sucede a su alrededor&#8221;<\/a><\/h4><div class=\"ultp-block-excerpt\"><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-29819\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/josep-maria-sole-para-innovar-hay-que-atreverse-y-el-atrevimiento-implica-asumir-el-riesgo-a-equivocarse\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Entrevista a Josep Maria Sol\u00e9 - Per innovar, cal atrevir-s&#039;hi\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-600x600.png\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/josep-maria-sole-para-innovar-hay-que-atreverse-y-el-atrevimiento-implica-asumir-el-riesgo-a-equivocarse\/\" >Josep Maria Sol\u00e9: &#8220;Para innovar, hay que atreverse, y el atrevimiento implica asumir el riesgo a equivocarse&#8221;<\/a><\/h4><div class=\"ultp-block-excerpt\"><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-28769\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/willy-allegre-el-rehab-lab-permite-que-los-usuarios-con-discapacidad-sean-actores-de-su-propia-rehabilitacion-y-de-su-proyecto-de-vida\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Willy All\u00e8gre en las instalaciones de CIM-UPC\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/09\/Entrevista-Willy-Allegre-600x600.png\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/willy-allegre-el-rehab-lab-permite-que-los-usuarios-con-discapacidad-sean-actores-de-su-propia-rehabilitacion-y-de-su-proyecto-de-vida\/\" >Willy All\u00e8gre: \u201cEl Rehab-Lab permite que los usuarios con discapacidad sean actores de su propia rehabilitaci\u00f3n y de su proyecto de vida\u201d<\/a><\/h4><div class=\"ultp-block-excerpt\">Willy All\u00e8gre es ingeniero e impulsor de la red Rehab-Lab, que cuenta con m\u00e1s de 50 Fab Labs en Francia y otros pa\u00edses que permiten la fabricaci\u00f3n 3D de ayudas funcionales para personas con discapacidades motoras. En iSocial lo entrevistamos con motivo del proyecto Rehab-Lab Cat, que extender\u00e1 la iniciativa a Catalu\u00f1a.<\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-24003\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/victoria-mandefield-la-soliguia-permite-a-los-profesionales-ganar-tiempo-para-el-trabajo-social-y-el-acompanamiento\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Victoria Mandefield, creadora de la Soligu\u00eda, en la sede de la Fundaci\u00f3n iSocial\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/04\/Victoria-Mandefield-creadora-de-la-Soliguia-a-la-seu-de-la-Fundacio-iSocial-600x600.png\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/victoria-mandefield-la-soliguia-permite-a-los-profesionales-ganar-tiempo-para-el-trabajo-social-y-el-acompanamiento\/\" >Victoria Mandefield: &#8220;La Soligu\u00eda permite a los profesionales ganar tiempo para el trabajo social y el acompa\u00f1amiento&#8221;<\/a><\/h4><div class=\"ultp-block-excerpt\">Hablamos con Victoria Mandefield, CEO de Solinum y creadora de la Soliguide, o Soligu\u00eda, buscador digital de recursos y organizaciones sociales para las personas en situaci\u00f3n de vulnerabilidad. Gracias al proyecto Solidigital, la Soligu\u00eda llega a Catalunya y se integrar\u00e1 con Nidus y con la aplicaci\u00f3n francesa Reconnect.<\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-13081\"><div class=\"ultp-block-content-wrap\"><div class=\"ultp-block-image ultp-block-image-zoomIn\"><a href=\"https:\/\/isocial.cat\/eu\/agusti-cerrillo-los-robots-conversacionales-o-chatbots-en-no-mucho-tiempo-podran-ser-utilizados-por-las-administraciones-publicas-para-mejorar-la-calidad-de-los-servicios-sociales\/\" ><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\"  class=\"ultp-block-image-content\"  alt=\"Agust\u00ed Cerrillo: &#8220;Los chatbots en no mucho tiempo podr\u00e1n ser utilizados para mejorar la calidad de los servicios sociales&#8221;\"  src=\"https:\/\/isocial.cat\/wp-content\/uploads\/2023\/01\/Agusti-Cerrillo-600x600.jpg\" \/><\/a><\/div><div class=\"ultp-block-content\"><div class=\"ultp-category-grid ultp-category-classic ultp-category-aboveTitle\"><div class=\"ultp-category-in\"><a class=\"ultp-cat-argitalpenak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/\"  >Argitalpenak<\/a><a class=\"ultp-cat-destacados-home-eu\" href=\"https:\/\/isocial.cat\/eu\/category\/destacados-home-eu\/\"  >Destacados Home<\/a><a class=\"ultp-cat-elkarrizketak\" href=\"https:\/\/isocial.cat\/eu\/category\/argitalpenak\/elkarrizketak\/\"  >Elkarrizketak<\/a><\/div><\/div><h4 class=\"ultp-block-title \"><a href=\"https:\/\/isocial.cat\/eu\/agusti-cerrillo-los-robots-conversacionales-o-chatbots-en-no-mucho-tiempo-podran-ser-utilizados-por-las-administraciones-publicas-para-mejorar-la-calidad-de-los-servicios-sociales\/\" >Agust\u00ed Cerrillo: &#8220;Los chatbots en no mucho tiempo podr\u00e1n ser utilizados para mejorar la calidad de los servicios sociales&#8221;<\/a><\/h4><div class=\"ultp-block-excerpt\">Hablamos con Agust\u00ed Cerrillo, catedr\u00e1tico de Derecho Administrativo de la UOC sobre el uso de inteligencia artificial en los servicios sociales.<\/div><\/div><\/div><\/div><\/div><div class=\"ultp-pagination-wrap ultp-pagination-ajax-action\" data-paged=\"1\" data-expost=\"\"  data-blockid=\"36b070\" data-postid=\"29816\" data-pages=\"2\" data-blockname=\"ultimate-post_post-grid-1\" data-selfpostid=\"yes\"><ul class=\"ultp-pagination\"><li class=\"ultp-prev-page-numbers\" style=\"display:none\"><a href=\"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\">\n  <path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"1.5\" d=\"m15 18-6-6 6-6\"\/>\n<\/svg>\n <\/a><\/li><li class=\"ultp-center-item pagination-active\" data-current=\"1\"><a href=\"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/\">1<\/a><\/li><li class=\"ultp-center-item\" data-current=\"2\" ><a href=\"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/page\/2\/\">2<\/a><\/li><li class=\"ultp-last-dot\" style=\"display:none\"><a href=\"#\">&#8230;<\/a><\/li><li class=\"ultp-next-page-numbers\"><a href=\"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/page\/2\/\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 24 24\">\n  <path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"1.5\" d=\"m9 18 6-6-6-6\"\/>\n<\/svg>\n<\/a><\/li><\/ul><\/div><\/div><div class=\"pagination-block-html\" aria-hidden=\"true\" style=\"display: none;\"><\/div><\/div>\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns footer-newsletter gb-layout-columns-1 one-column alignfull\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<div class=\"wp-block-genesis-blocks-gb-columns container gb-layout-columns-1 one-column\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c, .wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c[data-kb-block=\"kb-adv-heading_4d2423-9c\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c[data-kb-block=\"kb-adv-heading_4d2423-9c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading_4d2423-9c[data-kb-block=\"kb-adv-heading_4d2423-9c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading_4d2423-9c titol-seccio wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading_4d2423-9c\">Buletina<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29, .wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29[data-kb-block=\"kb-adv-heading_cf2667-29\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29[data-kb-block=\"kb-adv-heading_cf2667-29\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading_cf2667-29[data-kb-block=\"kb-adv-heading_cf2667-29\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading_cf2667-29 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading_cf2667-29\">Harpidetu zaitez gizarte-zerbitzuetako berrikuntzarakojoera guztien berri izan nahi baduzu.<\/h4>\n\n\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":29794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"categories":[277,284],"tags":[],"class_list":["post-29819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados-home-eu","category-elkarrizketak","with-featured-image"],"acf":[],"taxonomy_info":{"category":[{"value":277,"label":"Destacados Home"},{"value":284,"label":"Elkarrizketak"}]},"featured_image_src_large":["https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole.png",1200,630,false],"author_info":{"display_name":"Ferran Benito","author_link":"https:\/\/isocial.cat\/eu\/author\/fbenito\/"},"comment_info":0,"category_info":[{"term_id":277,"name":"Destacados Home","slug":"destacados-home-eu","term_group":0,"term_taxonomy_id":277,"taxonomy":"category","description":"","parent":0,"count":123,"filter":"raw","term_order":"0","cat_ID":277,"category_count":123,"category_description":"","cat_name":"Destacados Home","category_nicename":"destacados-home-eu","category_parent":0},{"term_id":284,"name":"Elkarrizketak","slug":"elkarrizketak","term_group":0,"term_taxonomy_id":284,"taxonomy":"category","description":"","parent":259,"count":8,"filter":"raw","term_order":"0","cat_ID":284,"category_count":8,"category_description":"","cat_name":"Elkarrizketak","category_nicename":"elkarrizketak","category_parent":259}],"tag_info":false,"featured_image_src":"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-600x400.png","featured_image_src_square":"https:\/\/isocial.cat\/wp-content\/uploads\/2024\/12\/Entrevista-a-Josep-Maria-Sole-600x600.png","_links":{"self":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/comments?post=29819"}],"version-history":[{"count":1,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/revisions"}],"predecessor-version":[{"id":29820,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/posts\/29819\/revisions\/29820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/media\/29794"}],"wp:attachment":[{"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/media?parent=29819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/categories?post=29819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isocial.cat\/eu\/wp-json\/wp\/v2\/tags?post=29819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}